{"id":14837,"date":"2026-09-01T12:06:39","date_gmt":"2026-09-01T19:06:39","guid":{"rendered":"https:\/\/swissnex.org\/sanfrancisco\/?page_id=14837"},"modified":"2026-09-01T12:06:39","modified_gmt":"2026-09-01T19:06:39","slug":"events-programs","status":"publish","type":"page","link":"https:\/\/swissnex.org\/sanfrancisco\/events-programs\/","title":{"rendered":"Events &#038; Programs"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":95,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"class_list":["post-14837","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Events &amp; Programs - Swissnex in San Francisco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/swissnex.org\/sanfrancisco\/events-programs\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Events &amp; Programs - Swissnex in San Francisco\" \/>\n<meta property=\"og:url\" content=\"https:\/\/swissnex.org\/sanfrancisco\/events-programs\/\" \/>\n<meta property=\"og:site_name\" content=\"Swissnex in San Francisco\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/swissnexsanfrancisco\" \/>\n<meta property=\"og:image\" content=\"https:\/\/swissnex.org\/app\/uploads\/sites\/6\/default.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@swissnexSF\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/swissnex.org\\\/sanfrancisco\\\/events-programs\\\/\",\"url\":\"https:\\\/\\\/swissnex.org\\\/sanfrancisco\\\/events-programs\\\/\",\"name\":\"Events & Programs - Swissnex in San Francisco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/swissnex.org\\\/sanfrancisco\\\/#website\"},\"datePublished\":\"2026-09-01T19:06:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/swissnex.org\\\/sanfrancisco\\\/events-programs\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/swissnex.org\\\/sanfrancisco\\\/events-programs\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/swissnex.org\\\/sanfrancisco\\\/events-programs\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/swissnex.org\\\/sanfrancisco\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events &#038; Programs\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/swissnex.org\\\/sanfrancisco\\\/#website\",\"url\":\"https:\\\/\\\/swissnex.org\\\/sanfrancisco\\\/\",\"name\":\"Swissnex in San Francisco\",\"description\":\"Connecting Switzerland, North America and the world in science, education, innovation, and the arts.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/swissnex.org\\\/sanfrancisco\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Events & Programs - Swissnex in San Francisco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/swissnex.org\/sanfrancisco\/events-programs\/","og_locale":"en_US","og_type":"article","og_title":"Events & Programs - Swissnex in San Francisco","og_url":"https:\/\/swissnex.org\/sanfrancisco\/events-programs\/","og_site_name":"Swissnex in San Francisco","article_publisher":"https:\/\/www.facebook.com\/swissnexsanfrancisco","og_image":[{"url":"https:\/\/swissnex.org\/app\/uploads\/sites\/6\/default.jpg","width":1200,"height":628,"type":"image\/jpg"}],"twitter_card":"summary_large_image","twitter_site":"@swissnexSF","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/swissnex.org\/sanfrancisco\/events-programs\/","url":"https:\/\/swissnex.org\/sanfrancisco\/events-programs\/","name":"Events & Programs - Swissnex in San Francisco","isPartOf":{"@id":"https:\/\/swissnex.org\/sanfrancisco\/#website"},"datePublished":"2026-09-01T19:06:39+00:00","breadcrumb":{"@id":"https:\/\/swissnex.org\/sanfrancisco\/events-programs\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/swissnex.org\/sanfrancisco\/events-programs\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/swissnex.org\/sanfrancisco\/events-programs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/swissnex.org\/sanfrancisco\/"},{"@type":"ListItem","position":2,"name":"Events &#038; Programs"}]},{"@type":"WebSite","@id":"https:\/\/swissnex.org\/sanfrancisco\/#website","url":"https:\/\/swissnex.org\/sanfrancisco\/","name":"Swissnex in San Francisco","description":"Connecting Switzerland, North America and the world in science, education, innovation, and the arts.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/swissnex.org\/sanfrancisco\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/swissnex.org\/sanfrancisco\/wp-json\/wp\/v2\/pages\/14837","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swissnex.org\/sanfrancisco\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/swissnex.org\/sanfrancisco\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/swissnex.org\/sanfrancisco\/wp-json\/wp\/v2\/users\/95"}],"replies":[{"embeddable":true,"href":"https:\/\/swissnex.org\/sanfrancisco\/wp-json\/wp\/v2\/comments?post=14837"}],"version-history":[{"count":1,"href":"https:\/\/swissnex.org\/sanfrancisco\/wp-json\/wp\/v2\/pages\/14837\/revisions"}],"predecessor-version":[{"id":14838,"href":"https:\/\/swissnex.org\/sanfrancisco\/wp-json\/wp\/v2\/pages\/14837\/revisions\/14838"}],"wp:attachment":[{"href":"https:\/\/swissnex.org\/sanfrancisco\/wp-json\/wp\/v2\/media?parent=14837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}